{"id":33705,"date":"2021-12-13T13:12:02","date_gmt":"2021-12-13T12:12:02","guid":{"rendered":"https:\/\/wbp.lublin.pl\/?p=33705"},"modified":"2021-12-14T17:14:58","modified_gmt":"2021-12-14T16:14:58","slug":"40-rocznica-wprowadzenie-stanu-wojennego-zapal-swiatlowolnosci","status":"publish","type":"post","link":"https:\/\/wbp.lublin.pl\/index.php\/2021\/12\/13\/40-rocznica-wprowadzenie-stanu-wojennego-zapal-swiatlowolnosci\/","title":{"rendered":"40. rocznica wprowadzenia stanu wojennego"},"content":{"rendered":"\n\n\n<p class=\"wp-block-paragraph\"><strong>Wystawy, koncerty, projekcje film\u00f3w, premiery ksi\u0105\u017cek, spacery tematyczne i widowiska &#8211; niemal 50 wydarze\u0144 w ca\u0142ym kraju upami\u0119tni 40. rocznic\u0119 wprowadzenia stanu wojennego w Polsce. Zach\u0119camy do zapoznania si\u0119 z wydarzeniami organizowanymi przez instytucje kultury prowadzone lub wsp\u00f3\u0142prowadzone przez Ministra Kultury i Dziedzictwa Narodowego.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img data-dominant-color=\"bd9493\" data-has-transparency=\"false\" style=\"--dominant-color: #bd9493;\" loading=\"lazy\" decoding=\"async\" sizes=\"auto, (max-width: 1460px) 100vw, 1460px\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/65ff83ae-93a0-460b-bad9-a2f0fde8a034.jpg\" alt=\"Stan wojenny-baner\" class=\"wp-image-33712 not-transparent\" width=\"730\" height=\"308\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Zobacz: <a href=\"https:\/\/www.gov.pl\/web\/kultura\/wydarzenia-upamietniajace-40-rocznice-wprowadzenia-stanu-wojennego-w-polsce\">Ministerstwo Kultury i Dziedzictwa Narodowego<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/swiatlowolnosci.ipn.gov.pl\/\">Zapal \u015bwiat\u0142o wolno\u015bci<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Instytut Pami\u0119ci Narodowej przy wsparciu Ministerstwa Kultury i Dziedzictwa Narodowego oraz Biura Programu \u201eNiepodleg\u0142a\u201d przygotowa\u0142o kampani\u0119 pod has\u0142em \u201eZapal \u015bwiat\u0142o wolno\u015bci\u201d. <\/strong>Akcja ma na celu upami\u0119tnienie wydarze\u0144 z grudnia 1981 roku &#8211; szczeg\u00f3lnie trudnych w polskiej historii.<strong> W jej ramach zapraszamy do symbolicznego uczczenia rocznicy poprzez zapalenie \u015bwiec w oknach dom\u00f3w 13 grudnia o godz. 19:30. Symboliczne \u015bwiat\u0142a zap\u0142on\u0105 r\u00f3wnie\u017c w wa\u017cnych miejscach na terenie ca\u0142ego kraju.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"3a3a3a\" data-has-transparency=\"false\" style=\"--dominant-color: #3a3a3a;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33738 not-transparent\" data-id=\"33738\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/20211213_1858131.jpg\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"4a2b13\" data-has-transparency=\"false\" style=\"--dominant-color: #4a2b13;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33736 not-transparent\" data-id=\"33736\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/IMG_63861.jpg\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"2a2017\" data-has-transparency=\"false\" style=\"--dominant-color: #2a2017;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33721 not-transparent\" data-id=\"33721\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/20211213_1847081.jpg\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"161208\" data-has-transparency=\"false\" style=\"--dominant-color: #161208;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33729 not-transparent\" data-id=\"33729\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/IMG_63701.jpg\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"0d0a08\" data-has-transparency=\"false\" style=\"--dominant-color: #0d0a08;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33723 not-transparent\" data-id=\"33723\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/20211213_1847361.jpg\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"161108\" data-has-transparency=\"false\" style=\"--dominant-color: #161108;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33730 not-transparent\" data-id=\"33730\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/IMG_63741.jpg\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"33281a\" data-has-transparency=\"false\" style=\"--dominant-color: #33281a;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33724 not-transparent\" data-id=\"33724\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/20211213_1847421.jpg\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"1a140a\" data-has-transparency=\"false\" style=\"--dominant-color: #1a140a;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33728 not-transparent\" data-id=\"33728\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/IMG_63681.jpg\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"1e150c\" data-has-transparency=\"false\" style=\"--dominant-color: #1e150c;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33725 not-transparent\" data-id=\"33725\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/20211213_1848511.jpg\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"251a0e\" data-has-transparency=\"false\" style=\"--dominant-color: #251a0e;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33734 not-transparent\" data-id=\"33734\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/IMG_63781.jpg\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"231a14\" data-has-transparency=\"false\" style=\"--dominant-color: #231a14;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33726 not-transparent\" data-id=\"33726\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/20211213_1851031.jpg\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"5a3619\" data-has-transparency=\"false\" style=\"--dominant-color: #5a3619;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33733 not-transparent\" data-id=\"33733\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/IMG_63761.jpg\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"120e08\" data-has-transparency=\"false\" style=\"--dominant-color: #120e08;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33727 not-transparent\" data-id=\"33727\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/20211213_1851151.jpg\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"4a2e16\" data-has-transparency=\"false\" style=\"--dominant-color: #4a2e16;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33731 not-transparent\" data-id=\"33731\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/IMG_63751.jpg\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"5c4733\" data-has-transparency=\"false\" style=\"--dominant-color: #5c4733;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33740 not-transparent\" data-id=\"33740\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/20211213_1858261.jpg\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"643e1f\" data-has-transparency=\"false\" style=\"--dominant-color: #643e1f;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33735 not-transparent\" data-id=\"33735\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/IMG_63831-rotated.jpg\"\/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-dominant-color=\"343434\" data-has-transparency=\"false\" style=\"--dominant-color: #343434;\" decoding=\"async\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-33737 not-transparent\" data-id=\"33737\" src=\"https:\/\/wbp.lublin.pl\/wp-content\/uploads\/2021\/12\/20211213_1857561.jpg\"\/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-style-large is-layout-flow wp-block-quote-is-layout-flow\"><p>Fot. <strong>Dorota Mo\u015bcibrodzka<\/strong><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Zapal #\u015awiat\u0142oWolno\u015bci<\/p>\n","protected":false},"author":7,"featured_media":33719,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_tec_requires_first_save":true,"pgc_sgb_lightbox_settings":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","footnotes":""},"categories":[641,643,10],"tags":[],"class_list":["post-33705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kalendarium-rocznic","category-kalendarium-rocznic-2021","category-aktualnosci"],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:38:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/posts\/33705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/comments?post=33705"}],"version-history":[{"count":16,"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/posts\/33705\/revisions"}],"predecessor-version":[{"id":33760,"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/posts\/33705\/revisions\/33760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/media\/33719"}],"wp:attachment":[{"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/media?parent=33705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/categories?post=33705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/tags?post=33705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}