{"id":9877,"date":"2017-03-03T09:21:11","date_gmt":"2017-03-03T08:21:11","guid":{"rendered":"https:\/\/wbp.lublin.pl8\/index.php\/2017\/03\/03\/nowe-czasopisma-w-wbp\/"},"modified":"2018-07-01T19:43:55","modified_gmt":"2018-07-01T17:43:55","slug":"nowe-czasopisma-w-wbp","status":"publish","type":"post","link":"https:\/\/wbp.lublin.pl\/index.php\/2017\/03\/03\/nowe-czasopisma-w-wbp\/","title":{"rendered":"Nowe czasopisma w WBP"},"content":{"rendered":"<p><!--more--><\/p>\n<div style=\"float: left; width: 40%; text-align: center;\"><img data-dominant-color=\"5a5c56\" data-has-transparency=\"false\" style=\"--dominant-color: #5a5c56;\" decoding=\"async\" class=\"size-full wp-image-9862 not-transparent\" src=\"http:\/\/wbp.lublin.pl\/wp-content\/uploads\/2017\/03\/wydarzenia_aktualnosci_2017_2017-03-03-czasopisma_1.JPG\" alt=\"\" height=\"100\" \/> <img data-dominant-color=\"ab9a9c\" data-has-transparency=\"false\" style=\"--dominant-color: #ab9a9c;\" decoding=\"async\" class=\"size-full wp-image-9863 not-transparent\" src=\"http:\/\/wbp.lublin.pl\/wp-content\/uploads\/2017\/03\/wydarzenia_aktualnosci_2017_2017-03-03-czasopisma_2.JPG\" alt=\"\" height=\"100\" \/> <img data-dominant-color=\"70524c\" data-has-transparency=\"false\" style=\"--dominant-color: #70524c;\" decoding=\"async\" class=\"size-full wp-image-9864 not-transparent\" src=\"http:\/\/wbp.lublin.pl\/wp-content\/uploads\/2017\/03\/wydarzenia_aktualnosci_2017_2017-03-03-czasopisma_3.JPG\" alt=\"\" height=\"100\" \/> <img data-dominant-color=\"636a5a\" data-has-transparency=\"false\" style=\"--dominant-color: #636a5a;\" decoding=\"async\" class=\"size-full wp-image-9865 not-transparent\" src=\"http:\/\/wbp.lublin.pl\/wp-content\/uploads\/2017\/03\/wydarzenia_aktualnosci_2017_2017-03-03-czasopisma_4.JPG\" alt=\"\" height=\"100\" \/> <img data-dominant-color=\"857165\" data-has-transparency=\"false\" style=\"--dominant-color: #857165;\" decoding=\"async\" class=\"size-full wp-image-9866 not-transparent\" src=\"http:\/\/wbp.lublin.pl\/wp-content\/uploads\/2017\/03\/wydarzenia_aktualnosci_2017_2017-03-03-czasopisma_5.JPG\" alt=\"\" height=\"100\" \/> <img data-dominant-color=\"453f3d\" data-has-transparency=\"false\" style=\"--dominant-color: #453f3d;\" decoding=\"async\" class=\"size-full wp-image-9867 not-transparent\" src=\"http:\/\/wbp.lublin.pl\/wp-content\/uploads\/2017\/03\/wydarzenia_aktualnosci_2017_2017-03-03-czasopisma_6.JPG\" alt=\"\" height=\"100\" \/> <img data-dominant-color=\"7f7884\" data-has-transparency=\"false\" style=\"--dominant-color: #7f7884;\" decoding=\"async\" class=\"size-full wp-image-9868 not-transparent\" src=\"http:\/\/wbp.lublin.pl\/wp-content\/uploads\/2017\/03\/wydarzenia_aktualnosci_2017_2017-03-03-czasopisma_7.JPG\" alt=\"\" height=\"100\" \/> <img data-dominant-color=\"7e8590\" data-has-transparency=\"false\" style=\"--dominant-color: #7e8590;\" decoding=\"async\" class=\"size-full wp-image-9869 not-transparent\" src=\"http:\/\/wbp.lublin.pl\/wp-content\/uploads\/2017\/03\/wydarzenia_aktualnosci_2017_2017-03-03-czasopisma_8.JPG\" alt=\"\" height=\"100\" \/><\/div>\n<div style=\"float: right; width: 60%;\">\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Z przyjemno\u015bci\u0105 informujemy, \u017ce z pocz\u0105tkiem 2017 roku Czytelnia Czasopism znacz\u0105co rozszerzy\u0142a prenumerat\u0119 udost\u0119pnianej prasy. W odpowiedzi na zg\u0142aszane przez czytelnik\u00f3w uwagi i zainteresowanie niedost\u0119pnymi do tej pory tytu\u0142ami, wzbogacili\u015bmy nasz\u0105 ofert\u0119 o czasopisma z r\u00f3\u017cnych dziedzin, w tym tak\u017ce o egzemplarze czasopism obcoj\u0119zycznych.<\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;\">Na sta\u0142e w naszej ofercie zago\u015bci\u0142y:<\/p>\n<ol>\n<li>Avanti<\/li>\n<li>Elle<\/li>\n<li>Forbes<\/li>\n<li>Fotografia Masterclass<\/li>\n<li>Harper&#8217;s Bazaar<\/li>\n<li>Komputer \u015awiat &#8211; Tw\u00f3j Niezb\u0119dnik<\/li>\n<li>LNE<\/li>\n<li>Magazyn Literacki Ksi\u0105\u017cki<\/li>\n<li>Men&#8217;s Health<\/li>\n<li>Newsweek Historia<\/li>\n<li>Przekr\u00f3j<\/li>\n<li>Sielskie \u017bycie<\/li>\n<li>\u015awiat Motocykli<\/li>\n<li>W Sieci<\/li>\n<li>Warszawska Gazeta<\/li>\n<li>Zielony Sztandar<\/li>\n<\/ol>\n<\/div>\n<p style=\"text-align: center;\"><img data-dominant-color=\"725e5d\" data-has-transparency=\"false\" style=\"--dominant-color: #725e5d;\" decoding=\"async\" class=\"size-full wp-image-9870 not-transparent\" src=\"http:\/\/wbp.lublin.pl\/wp-content\/uploads\/2017\/03\/wydarzenia_aktualnosci_2017_2017-03-03-czasopisma_9.JPG\" alt=\"\" height=\"100\" \/> <img data-dominant-color=\"9aa69d\" data-has-transparency=\"false\" style=\"--dominant-color: #9aa69d;\" decoding=\"async\" class=\"size-full wp-image-9871 not-transparent\" src=\"http:\/\/wbp.lublin.pl\/wp-content\/uploads\/2017\/03\/wydarzenia_aktualnosci_2017_2017-03-03-czasopisma_10.JPG\" alt=\"\" height=\"100\" \/> <img data-dominant-color=\"88848e\" data-has-transparency=\"false\" style=\"--dominant-color: #88848e;\" decoding=\"async\" class=\"size-full wp-image-9872 not-transparent\" src=\"http:\/\/wbp.lublin.pl\/wp-content\/uploads\/2017\/03\/wydarzenia_aktualnosci_2017_2017-03-03-czasopisma_11.JPG\" alt=\"\" height=\"100\" \/> <img data-dominant-color=\"605961\" data-has-transparency=\"false\" style=\"--dominant-color: #605961;\" decoding=\"async\" class=\"size-full wp-image-9873 not-transparent\" src=\"http:\/\/wbp.lublin.pl\/wp-content\/uploads\/2017\/03\/wydarzenia_aktualnosci_2017_2017-03-03-czasopisma_12.JPG\" alt=\"\" height=\"100\" \/> <img data-dominant-color=\"553a34\" data-has-transparency=\"false\" style=\"--dominant-color: #553a34;\" decoding=\"async\" class=\"size-full wp-image-9874 not-transparent\" src=\"http:\/\/wbp.lublin.pl\/wp-content\/uploads\/2017\/03\/wydarzenia_aktualnosci_2017_2017-03-03-czasopisma_13.JPG\" alt=\"\" height=\"100\" \/> <img data-dominant-color=\"9c8a88\" data-has-transparency=\"false\" style=\"--dominant-color: #9c8a88;\" decoding=\"async\" class=\"size-full wp-image-9875 not-transparent\" src=\"http:\/\/wbp.lublin.pl\/wp-content\/uploads\/2017\/03\/wydarzenia_aktualnosci_2017_2017-03-03-czasopisma_14.JPG\" alt=\"\" height=\"100\" \/> <img data-dominant-color=\"a4a2a1\" data-has-transparency=\"false\" style=\"--dominant-color: #a4a2a1;\" decoding=\"async\" class=\"size-full wp-image-9876 not-transparent\" src=\"http:\/\/wbp.lublin.pl\/wp-content\/uploads\/2017\/03\/wydarzenia_aktualnosci_2017_2017-03-03-czasopisma_15.JPG\" alt=\"\" height=\"100\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":9861,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_tec_requires_first_save":true,"pgc_sgb_lightbox_settings":"","_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","footnotes":""},"categories":[10,53],"tags":[],"class_list":["post-9877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci","category-komunikaty"],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 11:20:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/posts\/9877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/comments?post=9877"}],"version-history":[{"count":3,"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/posts\/9877\/revisions"}],"predecessor-version":[{"id":12361,"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/posts\/9877\/revisions\/12361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/media\/9861"}],"wp:attachment":[{"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/media?parent=9877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/categories?post=9877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wbp.lublin.pl\/index.php\/wp-json\/wp\/v2\/tags?post=9877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}